{"id":992,"date":"2011-07-08T14:19:53","date_gmt":"2011-07-08T14:19:53","guid":{"rendered":""},"modified":"2022-09-25T21:41:37","modified_gmt":"2022-09-26T01:41:37","slug":"legal-network-news-42-july-2011","status":"publish","type":"publication22","link":"https:\/\/www.hivlegalnetwork.ca\/site\/legal-network-news-42-july-2011\/","title":{"rendered":"Legal Network News 42 &#8211; July 2011"},"content":{"rendered":"<p class=\"download-link-button\"><a class=\"download-link en\" title=\"Legal Network News 42 \u2013 July 2011\" href=\"https:\/\/www.hivlegalnetwork.ca\/site\/download\/12442\/?tmstv=1778633939\" rel=\"nofollow\">\r\n\tDownload<\/a><\/p>","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"publication_topics":[145,147,158,161],"publication_type":[177],"publication_language":[184,185],"class_list":["post-992","publication22","type-publication22","status-publish","hentry","publication_topics-access-to-medicines","publication_topics-drug-policy","publication_topics-sex-work","publication_topics-womens-rights","publication_type-legal-network-news","publication_language-english","publication_language-french"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hivlegalnetwork.ca\/site\/wp-json\/wp\/v2\/publication22\/992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hivlegalnetwork.ca\/site\/wp-json\/wp\/v2\/publication22"}],"about":[{"href":"https:\/\/www.hivlegalnetwork.ca\/site\/wp-json\/wp\/v2\/types\/publication22"}],"author":[{"embeddable":true,"href":"https:\/\/www.hivlegalnetwork.ca\/site\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":4,"href":"https:\/\/www.hivlegalnetwork.ca\/site\/wp-json\/wp\/v2\/publication22\/992\/revisions"}],"predecessor-version":[{"id":21291,"href":"https:\/\/www.hivlegalnetwork.ca\/site\/wp-json\/wp\/v2\/publication22\/992\/revisions\/21291"}],"wp:attachment":[{"href":"https:\/\/www.hivlegalnetwork.ca\/site\/wp-json\/wp\/v2\/media?parent=992"}],"wp:term":[{"taxonomy":"publication_topics","embeddable":true,"href":"https:\/\/www.hivlegalnetwork.ca\/site\/wp-json\/wp\/v2\/publication_topics?post=992"},{"taxonomy":"publication_type","embeddable":true,"href":"https:\/\/www.hivlegalnetwork.ca\/site\/wp-json\/wp\/v2\/publication_type?post=992"},{"taxonomy":"publication_language","embeddable":true,"href":"https:\/\/www.hivlegalnetwork.ca\/site\/wp-json\/wp\/v2\/publication_language?post=992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}